{"id":1798,"date":"2022-06-02T20:26:49","date_gmt":"2022-06-02T20:26:49","guid":{"rendered":"http:\/\/visitflorencemuseums.com\/?p=1798"},"modified":"2023-06-09T09:06:19","modified_gmt":"2023-06-09T09:06:19","slug":"complesso-degli-uffizi-a-firenze","status":"publish","type":"post","link":"https:\/\/visitflorencemuseums.com\/it\/uffizi-complex-in-florence\/","title":{"rendered":"Il Complesso degli Uffizi di Firenze \u00e8 diventato il sito culturale pi\u00f9 visitato d&#039;Italia"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a href=\"http:\/\/visitflorencemuseums.com\/it\/exhibition\/uffizi\/\">Gli Uffizi <\/a>supera il Colosseo per numero di turisti nel 2021, la prima volta per il celebre complesso museale fiorentino che ospita anche Palazzo Pitti e il Giardino di Boboli. La classifica annuale \u00e8 stata creata nel&nbsp;<em>Giornale dell&#039;Arte<\/em>&nbsp;rivista d&#039;arte e&nbsp;<em>Il giornale d&#039;arte<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il numero totale di persone che hanno visitato gli Uffizi nel 2021 \u00e8 stato di circa 1,7 milioni, ovvero quasi 100.000 in pi\u00f9 rispetto al Colosseo, che si \u00e8 classificato al secondo posto (il Colosseo \u00e8 stato costantemente per molti anni l&#039;attrazione pi\u00f9 visitata in Italia, anche nel 2020, che \u00e8 stato l&#039;anno della pandemia).<\/p>\n\n\n<style>.kb-row-layout-id_b434a8-bf > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_b434a8-bf > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_b434a8-bf > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id_b434a8-bf > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_b434a8-bf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id_b434a8-bf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_b434a8-bf alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_d86159-31 > .kt-inside-inner-col,.kadence-column_d86159-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_d86159-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_d86159-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_d86159-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_d86159-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_d86159-31{position:relative;}@media all and (max-width: 1024px){.kadence-column_d86159-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_d86159-31 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_d86159-31\"><div class=\"kt-inside-inner-col\"><style>.kb-image_0b4809-bb .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image_0b4809-bb\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"300\" src=\"http:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/UFFIZI-GALLERY-11.jpg\" alt=\"GALLERIA DEGLI UFFIZI\" class=\"kb-img wp-image-3575\" title=\"\" srcset=\"https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/UFFIZI-GALLERY-11.jpg 500w, https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/UFFIZI-GALLERY-11-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">Il numero si riferisce a coloro che visitano la Galleria degli Uffizi, che ospita le opere pi\u00f9 celebri, tra cui la Nascita di Venere e la Primavera di Botticelli, il Tondo Doni di Michelangelo e l&#039;Annunciazione e l&#039;Adorazione dei Magi di Leonardo, solo per citarne alcune. Si riferisce anche al Giardino di Boboli e ai quattro musei di Palazzo Pitti (la Galleria Palatina, il Tesoro dei Granduchi, il Museo della Moda e del Costume e la Galleria d&#039;Arte Moderna).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al terzo posto si classifica il Parco Archeologico di Pompei, che ha anch&#039;esso superato il milione di visitatori. Seguono la Galleria dell&#039;Accademia di Firenze e la Reggia di Caserta, con meno di 500.000 visitatori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prima volta che il <strong><a href=\"http:\/\/visitflorencemuseums.com\/it\/galleria-degli-uffizi\/\" target=\"_blank\" data-type=\"page\" data-id=\"2643\" rel=\"noreferrer noopener\">Uffizi<\/a><\/strong> ha sconfitto anche la sua controparte, i Musei Vaticani, che tecnicamente non si trovano in Italia; tuttavia, fanno parte dello Stato del Vaticano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre a questo, gli Uffizi sono stati anche quelli che in passato hanno attirato il maggior numero di persone alle loro mostre speciali, come la celebrazione dell&#039;artista contemporaneo Giuseppe Penone, noto per le sue imponenti sculture di alberi, che si \u00e8 rivelata un grande successo, cos\u00ec come gli eventi che hanno accolto&nbsp;<em>Leone X torna a Firenze<\/em>&nbsp;a Palazzo Pitti, in concomitanza con la conclusione delle celebrazioni raffaellesche nel 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alcuni attribuiscono la crescita del complesso degli Uffizi ai miglioramenti apportati in passato dal direttore degli Uffizi Eike Schmidt, il quale ha dichiarato che queste cifre positive erano il risultato di uno &quot;sforzo di squadra&quot;, commentando: &quot;Siamo di nuovo su una traiettoria ascendente che fa ben sperare per il futuro&quot;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre a dare spazio all&#039;arte contemporanea all&#039;interno di quello che \u00e8 noto come il museo d&#039;arte sacra per l&#039;arte rinascimentale, Schmidt organizz\u00f2 mostre con artiste donne e artisti di gruppi sottorappresentati. Sotto la sua guida, <a href=\"http:\/\/visitflorencemuseums.com\/it\/exhibition\/uffizi\/\">gli Uffizi<\/a> ha inoltre introdotto il moderno sistema di biglietteria e ha riaperto le opere dai depositi per consentirne l&#039;esposizione; ha inoltre creato un&#039;iniziativa denominata Uffizi Diffusi per prestare alcune delle sue opere ai musei di tutta la Toscana e ha riaperto sale precedentemente chiuse e sezioni degli Uffizi e di Palazzo Pitti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IL &#039;<strong><a href=\"http:\/\/visitflorencemuseums.com\/it\/musei-gratuiti-a-firenze-tutte-le-date\/\" target=\"_blank\" data-type=\"page\" data-id=\"4543\" rel=\"noreferrer noopener\">ingresso gratuito la prima domenica<\/a><\/strong> L&#039;evento di ogni mese \u00e8 stato ripreso dopo la sospensione causata dalla pandemia. \u00c8 stato un evento da record per gli Uffizi, che lo hanno classificato come il weekend pi\u00f9 gettonato dal 2019.<\/p>\n\n\n\n<div data-vi-partner-id=\"P00058331\" data-vi-language=\"en\" data-vi-currency=\"USD\" data-vi-partner-type=\"AFFILIATE\" data-vi-url=\"https:\/\/www.viator.com\/Florence-attractions\/Uffizi-Gallery\/d519-a117\" data-vi-total-products=\"6\"><\/div>\n\n<script async=\"\" src=\"https:\/\/www.viator.com\/orion\/partner\/widget.js\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/visitflorencemuseums.com\/it\/a-guide-to-the-cathedral-complex-in-florence-our-top-tips\/\">Potrebbe interessarti anche<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Nel 2021, gli Uffizi superano il Colosseo per numero di turisti: \u00e8 la prima volta per il celebre complesso museale fiorentino che ospita anche Palazzo Pitti e il Giardino di Boboli. <\/p>","protected":false},"author":1,"featured_media":4625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[18,19],"tags":[],"class_list":["post-1798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tours","category-news"],"_links":{"self":[{"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/posts\/1798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/comments?post=1798"}],"version-history":[{"count":2,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/posts\/1798\/revisions"}],"predecessor-version":[{"id":4693,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/posts\/1798\/revisions\/4693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/media\/4625"}],"wp:attachment":[{"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/media?parent=1798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/categories?post=1798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/it\/wp-json\/wp\/v2\/tags?post=1798"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}