{"id":2491,"date":"2022-06-17T08:35:26","date_gmt":"2022-06-17T08:35:26","guid":{"rendered":"http:\/\/visitflorencemuseums.com\/?p=2491"},"modified":"2024-05-23T08:29:07","modified_gmt":"2024-05-23T08:29:07","slug":"la-catedral-de-florencia","status":"publish","type":"post","link":"https:\/\/visitflorencemuseums.com\/es_ve\/the-cathedral-of-florence\/","title":{"rendered":"La Catedral de Florencia es una de las maravillas de Italia."},"content":{"rendered":"<p class=\"wp-block-paragraph\">La Catedral de Florencia, o Santa Mar\u00eda del Fiore, es la tercera iglesia m\u00e1s grande del mundo, despu\u00e9s de <strong><a href=\"https:\/\/www.visitromemuseums.com\/st-peters-basilica\/\" target=\"_blank\" rel=\"noreferrer noopener\">San Pedro en Roma<\/a><\/strong> y la Catedral de San Pablo en Londres. Mide 153 metros de largo, 90 metros de alto y 90 metros de ancho.<\/p>\n\n\n\n<div data-tiqets-widget=\"discovery\" data-cards-layout=\"responsive\" data-content-type=\"venue\" data-item_count=\"3\" data-destination-type=\"city\" data-destination-id=\"71854\" data-partner=\"visit_florence_museums\"><\/div>\n<script> const tq_script = document.createElement(\"script\"); tq_script.src =\"https:\/\/widgets.tiqets.com\/loader.js\";  tq_script.defer=true; document.body.appendChild(tq_script);<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Creado al estilo de <strong>Arnolfo di Cambio<\/strong> y dedicada por Arnolfo di Cambio por Arnolfo di Cambio, fue dedicada a Santa Maria del Fiore; la flor (&#039;fiore&#039;) en cuesti\u00f3n es una referencia al lirio, que es un s\u00edmbolo simb\u00f3lico de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Santa Mar\u00eda del Fiore<\/strong> Se construy\u00f3 sobre una catedral, la segunda construida en Florencia, dedicada a Santa Reparata. En la cripta se pueden admirar los restos de la antigua iglesia. Estos, descubiertos durante el siglo XX, constituyen la evidencia m\u00e1s significativa de los inicios del cristianismo en Florencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Debido al tiempo que tom\u00f3 construir esta Catedral de Florencia (1296 \u2013 1436), la estructura tiene estilos distintos, que reflejan el per\u00edodo durante el cual se complet\u00f3 cada parte.<br>La fachada est\u00e1 adornada con paneles de m\u00e1rmol coloreados en tonos rosa y verde con bordes blancos.<\/p>\n\n\n<style>.kb-row-layout-id2491_880e47-4b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2491_880e47-4b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2491_880e47-4b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2491_880e47-4b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2491_880e47-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2491_880e47-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2491_880e47-4b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2491_025786-9e > .kt-inside-inner-col,.kadence-column2491_025786-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2491_025786-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2491_025786-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column2491_025786-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2491_025786-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2491_025786-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column2491_025786-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2491_025786-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2491_025786-9e\"><div class=\"kt-inside-inner-col\"><style>.kb-image2491_dae740-4f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2491_dae740-4f\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"480\" src=\"http:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/06\/34.jpg\" alt=\"La Catedral de Florencia\" class=\"kb-img wp-image-4640\" title=\"\" srcset=\"https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/06\/34.jpg 730w, https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/06\/34-300x197.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><figcaption>La Catedral de Florencia<\/figcaption><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><br>El <strong>Catedral de Florencia<\/strong> Tambi\u00e9n conocida como la Catedral, se encuentra en la Piazza del Duomo, donde se encuentran el Baptisterio y el Campanile de Giotto. Juntos, conforman el complejo de la Catedral, declarado Patrimonio de la Humanidad por la Unesco y que abarca todo el centro hist\u00f3rico de Florencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El complejo de la Catedral es la principal atracci\u00f3n tur\u00edstica de Florencia y, con frecuencia, el primer lugar que visitan los turistas de camino a Florencia. Por eso, se recomienda reservar las entradas con antelaci\u00f3n, sobre todo si planea subir a la famosa c\u00fapula de Brunelleschi y al Campanile de Giotto. Hay muchos escalones, \u00a1pero merece la pena!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La Catedral de Florencia hoy:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Hoy en d\u00eda, es posible recorrer las terrazas de la Catedral para disfrutar de una impresionante vista del centro de Florencia y las colinas circundantes. Tambi\u00e9n ofrece una vista en profundidad de los suelos de m\u00e1rmol recientemente restaurados, as\u00ed como de la impresionante c\u00fapula de Brunelleschi y el campanario de Giotto.<\/p>\n\n\n\n<div data-tiqets-widget=\"discovery\" data-cards-layout=\"responsive\" data-content-type=\"product\" data-item_count=\"3\" data-destination-type=\"venue\" data-destination-id=\"145662\" data-partner=\"visit_florence_museums\"><\/div>\n<script> const tq_script = document.createElement(\"script\"); tq_script.src =\"https:\/\/widgets.tiqets.com\/loader.js\";  tq_script.defer=true; document.body.appendChild(tq_script);<\/script>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/visitflorencemuseums.com\/es_ve\/el-tesoro-de-italia-de-giorgio-vasari\/\">Tambi\u00e9n te podr\u00eda interesar<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.kb-row-layout-id2491_66cde6-26 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2491_66cde6-26 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2491_66cde6-26 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id2491_66cde6-26 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2491_66cde6-26 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2491_66cde6-26 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2491_66cde6-26 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2491_04dd25-f2 > .kt-inside-inner-col,.kadence-column2491_04dd25-f2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2491_04dd25-f2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2491_04dd25-f2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2491_04dd25-f2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2491_04dd25-f2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2491_04dd25-f2{position:relative;}@media all and (max-width: 1024px){.kadence-column2491_04dd25-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2491_04dd25-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2491_04dd25-f2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap{border-bottom:10px solid #87d9fe;border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:rgba(153, 238, 245, 0.45);padding-top:3px;padding-right:3px;padding-bottom:3px;padding-left:3px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap:hover{background:#fffcfc;}.kt-info-box_5ca5ff-4d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box_5ca5ff-4d .kadence-info-box-image-inner-intrisic-container{max-width:500px;}.kt-info-box_5ca5ff-4d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:75%;width:500px;height:0px;max-width:100%;}.kt-info-box_5ca5ff-4d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box_5ca5ff-4d .kt-info-svg-icon-flip, .kt-info-box_5ca5ff-4d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-media{color:#444444;border-radius:4px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-left:0px;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;}.kt-info-box_5ca5ff-4d .kt-infobox-textcontent h3.kt-blocks-info-box-title{text-transform:uppercase;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box_5ca5ff-4d .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap{box-shadow:3px 2px 8px 2px rgba(0, 0, 0, 0);}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 9px 0px rgba(0, 0, 0, 0.2);}@media all and (max-width: 1024px){.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap{border-bottom:10px solid #87d9fe;box-shadow:3px 2px 8px 2px rgba(0, 0, 0, 0);}}@media all and (max-width: 1024px){.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 9px 0px rgba(0, 0, 0, 0.2);}}@media all and (max-width: 767px){.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap{border-bottom:10px solid #87d9fe;box-shadow:3px 2px 8px 2px rgba(0, 0, 0, 0);}.kt-info-box_5ca5ff-4d .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 9px 0px rgba(0, 0, 0, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box_5ca5ff-4d\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\" href=\"http:\/\/visitflorencemuseums.com\/es_ve\/bobili-gardens\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land43\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/Boboli-Gardens-1.jpg\" alt=\"Jardines de Boboli\" width=\"500\" height=\"300\" class=\"kt-info-box-image wp-image-3581\" title=\"\" srcset=\"https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/Boboli-Gardens-1.jpg 500w, https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/Boboli-Gardens-1-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Jardines de Boboli<\/h3><p class=\"kt-blocks-info-box-text\">Giardino di Boboli, o Jardines de Boboli, es un parque hist\u00f3rico de Florencia que se abri\u00f3 al p\u00fablico en 1766.<\/p><\/div><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2491_8fb25e-6b > .kt-inside-inner-col,.kadence-column2491_8fb25e-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2491_8fb25e-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2491_8fb25e-6b > .kt-inside-inner-col{flex-direction:column;}.kadence-column2491_8fb25e-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2491_8fb25e-6b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2491_8fb25e-6b{position:relative;}@media all and (max-width: 1024px){.kadence-column2491_8fb25e-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2491_8fb25e-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2491_8fb25e-6b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap{border-bottom:10px solid #87d9fe;border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;background:rgba(153, 238, 245, 0.45);padding-top:3px;padding-right:3px;padding-bottom:3px;padding-left:3px;margin-top:0px;margin-right:0px;margin-left:0px;}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap:hover{background:#fffcfc;}.kt-info-box_2440c0-5f.wp-block-kadence-infobox{max-width:100%;}.kt-info-box_2440c0-5f .kadence-info-box-image-inner-intrisic-container{max-width:500px;}.kt-info-box_2440c0-5f .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:75%;width:500px;height:0px;max-width:100%;}.kt-info-box_2440c0-5f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box_2440c0-5f .kt-info-svg-icon-flip, .kt-info-box_2440c0-5f .kt-blocks-info-box-number{font-size:50px;}.kt-info-box_2440c0-5f .kt-blocks-info-box-media{color:#444444;border-radius:4px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box_2440c0-5f .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;}.kt-info-box_2440c0-5f .kt-infobox-textcontent h3.kt-blocks-info-box-title{text-transform:uppercase;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box_2440c0-5f .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box_2440c0-5f .kt-blocks-info-box-text{min-height:100px;}.kt-info-box_2440c0-5f .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap{box-shadow:3px 2px 8px 2px rgba(0, 0, 0, 0);}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 9px 0px rgba(0, 0, 0, 0.2);}@media all and (max-width: 1024px){.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap{border-bottom:10px solid #87d9fe;box-shadow:3px 2px 8px 2px rgba(0, 0, 0, 0);}}@media all and (max-width: 1024px){.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 9px 0px rgba(0, 0, 0, 0.2);}}@media all and (max-width: 767px){.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap{border-bottom:10px solid #87d9fe;box-shadow:3px 2px 8px 2px rgba(0, 0, 0, 0);}.kt-info-box_2440c0-5f .kt-blocks-info-box-link-wrap:hover{box-shadow:0px 0px 9px 0px rgba(0, 0, 0, 0.2);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box_2440c0-5f\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\" href=\"http:\/\/visitflorencemuseums.com\/es_ve\/galeria-de-los-uffizi\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land43\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/UFFIZI-GALLERY-11.jpg\" alt=\"GALER\u00cdA DE LOS UFFIZI\" width=\"500\" height=\"300\" class=\"kt-info-box-image wp-image-3575\" title=\"\" srcset=\"https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/UFFIZI-GALLERY-11.jpg 500w, https:\/\/visitflorencemuseums.com\/wp-content\/uploads\/2022\/08\/UFFIZI-GALLERY-11-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">GALER\u00cdA DE LOS UFFIZI<\/h3><p class=\"kt-blocks-info-box-text\">El museo y galer\u00eda de arte m\u00e1s famoso de Florencia, la Galer\u00eda Uffizi, exhibe hermosas pinturas y esculturas.<\/p><\/div><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La Catedral de Florencia, o Santa Mar\u00eda del Fiore, es la tercera iglesia m\u00e1s grande del mundo, despu\u00e9s de San Pedro en Roma y San Pablo en Londres.<\/p>","protected":false},"author":1,"featured_media":4639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-2491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-museums"],"_links":{"self":[{"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/posts\/2491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/comments?post=2491"}],"version-history":[{"count":3,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/posts\/2491\/revisions"}],"predecessor-version":[{"id":5098,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/posts\/2491\/revisions\/5098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/media\/4639"}],"wp:attachment":[{"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/media?parent=2491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/categories?post=2491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitflorencemuseums.com\/es_ve\/wp-json\/wp\/v2\/tags?post=2491"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}